{"id":11982,"date":"2021-01-10T13:41:30","date_gmt":"2021-01-10T13:41:30","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=11982"},"modified":"2021-01-10T13:41:30","modified_gmt":"2021-01-10T13:41:30","slug":"jovem-de-18-anos-e-rendido-em-bar-e-levado-para-matagal-em-arapiraca","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/01\/10\/jovem-de-18-anos-e-rendido-em-bar-e-levado-para-matagal-em-arapiraca\/","title":{"rendered":"Jovem de 18 anos \u00e9 rendido em bar e levado para matagal em Arapiraca"},"content":{"rendered":"<p>Ainda s\u00e3o escassas as motiva\u00e7\u00f5es e autoria de uma tentativa de homic\u00eddio registrada na madrugada deste domingo (10), na zona rural do munic\u00edpio de Arapiraca, Agreste de Alagoas.<\/p>\n<p>De acordo com informa\u00e7\u00f5es do 3\u00ba Batalh\u00e3o de Pol\u00edcia Militar (3\u00ba BPM), era por volta das 1h quando a guarni\u00e7\u00e3o motorizada de For\u00e7a Tarefa 02 foi acionada para prestar apoio ao Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) a uma v\u00edtima de arma de fogo.<\/p>\n<p>No local indicado, os policiais constataram que a v\u00edtima, de 18 anos, estava bebendo em um bar quando foi rendida por um homem e levada a um matagal onde foi alvejada com um tiro na regi\u00e3o da cabe\u00e7a.<\/p>\n<p>O jovem foi socorrido com vida e levado ao Hospital de Emerg\u00eancia do Agreste (HEA).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: 7 Segundos<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainda s\u00e3o escassas as motiva\u00e7\u00f5es e autoria de uma tentativa de homic\u00eddio registrada na madrugada deste domingo (10), na zona rural do munic\u00edpio de Arapiraca, Agreste de Alagoas. De acordo com informa\u00e7\u00f5es do 3\u00ba Batalh\u00e3o de Pol\u00edcia Militar (3\u00ba BPM), era por volta das 1h quando a guarni\u00e7\u00e3o motorizada de For\u00e7a Tarefa 02 foi acionada &hellip;<\/p>\n","protected":false},"author":1,"featured_media":11983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11982"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11982\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}