{"id":12005,"date":"2021-01-11T19:19:17","date_gmt":"2021-01-11T19:19:17","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12005"},"modified":"2021-01-11T19:19:17","modified_gmt":"2021-01-11T19:19:17","slug":"clube-de-alagoas-ve-chance-de-proposta-por-marinho-e-tenta-provar-passagem","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/01\/11\/clube-de-alagoas-ve-chance-de-proposta-por-marinho-e-tenta-provar-passagem\/","title":{"rendered":"Clube de Alagoas v\u00ea chance de proposta por Marinho e tenta provar passagem"},"content":{"rendered":"<p>O Sport Club Penedense, clube mais antigo de Alagoas, tenta provar na Justi\u00e7a que o atacante Marinho atuou por l\u00e1 entre janeiro de 2003 e junho de 2006, dos 12 aos 16 anos. O documento emitido pela Confedera\u00e7\u00e3o Brasileira de Futebol (CBF) sobre a carreira do jogador atualmente no Santos consta s\u00f3 informa\u00e7\u00f5es a partir de 2006, o que mobiliza o modesto time nordestino nos bastidores.<\/p>\n<p>O medo do Penedense \u00e9 que o atacante, semifinalista da Copa Libertadores, na melhor fase da carreira, seja negociado no mercado da bola nos pr\u00f3ximos meses e o clube n\u00e3o tenha direito de receber a porcentagem equivalente ao mecanismo de solidariedade da Fifa, criado para recompensar financeiramente todos os clubes que participaram da forma\u00e7\u00e3o de um atleta, dos 12 aos 23 anos.<\/p>\n<p><a href=\"https:\/\/oparanews.com.br\/clube-de-alagoas-ve-chance-de-proposta-por-marinho-e-tenta-provar-passagem\/sem-titulo-2178\/\" rel=\"attachment wp-att-12006\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12006\" src=\"https:\/\/oparanews.com.br\/wp-content\/uploads\/2021\/01\/Sem-t\u00edtulo-56.jpg\" alt=\"\" width=\"450\" height=\"600\" \/><\/a>Marinho j\u00e1 teve transfer\u00eancias com altas cifras na carreira: do Vit\u00f3ria ao Changchun Yatai, da China, por R$ 17 milh\u00f5es, em 2017, e do clube asi\u00e1tico para o Gr\u00eamio, no ano seguinte, por cerca de R$ 8 milh\u00f5es. Em maio de 2019, o Santos pagou ao time ga\u00facho R$ 3 milh\u00f5es, mais os direitos econ\u00f4micos do zagueiro David Braz em troca, pelo atacante que hoje soma 64 jogos e 30 gols.<\/p>\n<p>O Penedense teria direito a algo pr\u00f3ximo de 1% desses valores, mas como n\u00e3o h\u00e1 registro da passagem nada foi recebido. Dirigentes ouviram nos bastidores a possibilidade de uma grande oferta de um clube dos Emirados \u00c1rabes por Marinho nas pr\u00f3ximas semanas e decidiram intensificar esfor\u00e7os para provar a tal passagem com s\u00famulas de jogos, imagens do jogador crian\u00e7a com a camisa do time e at\u00e9 v\u00eddeos publicados nas redes sociais em que Marinho afirma que iniciou sua carreira no Penedense.<\/p>\n<p>&#8220;Houve uma tentativa em 2017, quando ele [Marinho] estava na China, mas a CBF n\u00e3o tinha como alterar o passaporte desportivo porque, segundo o que ouvi, a Fifa n\u00e3o estava permitindo em raz\u00e3o do excesso de altera\u00e7\u00f5es de registros nos anos anteriores. Isso acontece porque muitas federa\u00e7\u00f5es eram prec\u00e1rias nos registros de jovens jogadores e os clubes descobrem os fatos aos poucos. O problema \u00e9 que at\u00e9 hoje n\u00e3o consta o registro do Marinho, ent\u00e3o a diretoria do Penedense me ligou para ver o que precisava ser feito em uma nova tentativa&#8221;, esclarece Marcelo Amoretty Souza, advogado especializado em direito desportivo, que ainda completa:<\/p>\n<p>&#8220;Quero ver se at\u00e9 o come\u00e7o da semana que vem damos entrada no pedido. \u00c9 um tr\u00e2mite interno que envolve Federa\u00e7\u00e3o Alagoana, CBF e Fifa. H\u00e1 um precedente recente de um clube que conseguiu comprovar um per\u00edodo sem registro e a Fifa autorizou, \u00e9 o que vamos tentar fazer. Se houver uma transfer\u00eancia do Marinho essa porcentagem pode ajudar muito o Penedense.&#8221;<\/p>\n<p>Hoje, h\u00e1 registros de Marinho nos seguintes clubes: Santa Rita\/Corinthians Alagoano (2006 a 2009), Fluminense (2007 e 2008), Internacional (2009 a 2013), Caxias (2011), Paran\u00e1 (2012), Ituano (2013), N\u00e1utico (2014), Cear\u00e1 (2015), Cruzeiro (2015 a 2018), Vit\u00f3ria (2016 a 2018), Changchun Yatai (2017 e 2018), Gr\u00eamio (2018 e 2019) e Santos (a partir de 2019). Ele tem contrato at\u00e9 31 de dezembro de 2022.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: UOL<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sport Club Penedense, clube mais antigo de Alagoas, tenta provar na Justi\u00e7a que o atacante Marinho atuou por l\u00e1 entre janeiro de 2003 e junho de 2006, dos 12 aos 16 anos. O documento emitido pela Confedera\u00e7\u00e3o Brasileira de Futebol (CBF) sobre a carreira do jogador atualmente no Santos consta s\u00f3 informa\u00e7\u00f5es a partir &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12005"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12005\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}