{"id":12076,"date":"2021-01-13T13:52:28","date_gmt":"2021-01-13T13:52:28","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12076"},"modified":"2021-01-13T13:52:28","modified_gmt":"2021-01-13T13:52:28","slug":"anvisa-decidira-uso-emergencial-de-vacinas-no-domingo","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/01\/13\/anvisa-decidira-uso-emergencial-de-vacinas-no-domingo\/","title":{"rendered":"Anvisa decidir\u00e1 uso emergencial de vacinas no domingo"},"content":{"rendered":"<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) informou que est\u00e1 prevista para domingo a reuni\u00e3o da Diretoria Colegiada que decidir\u00e1 sobre pedidos de autoriza\u00e7\u00e3o para uso emergencial, tempor\u00e1rio e experimental, das vacinas contra covid-19 do Instituto Butantan e da Fiocruz, respectivamente a CoronaVac e a AstraZeneca-Oxford.<\/p>\n<p>&#8220;A data representa o pen\u00faltimo dia do prazo estabelecido pela pr\u00f3pria ag\u00eancia como meta para an\u00e1lise dos pedidos&#8221;, acrescentou o comunicado da assessoria do \u00f3rg\u00e3o regulador.<\/p>\n<p>A Anvisa disse ainda que, para tanto, \u00e9 necess\u00e1ria a entrega em tempo h\u00e1bil para a an\u00e1lise &#8220;dos documentos faltantes e complementares&#8221;.<\/p>\n<p>Butantan e Fiocruz apresentaram na sexta-feira passada pedido de uso emergencial das vacinas contra covid-19.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) informou que est\u00e1 prevista para domingo a reuni\u00e3o da Diretoria Colegiada que decidir\u00e1 sobre pedidos de autoriza\u00e7\u00e3o para uso emergencial, tempor\u00e1rio e experimental, das vacinas contra covid-19 do Instituto Butantan e da Fiocruz, respectivamente a CoronaVac e a AstraZeneca-Oxford. &#8220;A data representa o pen\u00faltimo dia do prazo estabelecido &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12076"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12076\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}