{"id":12531,"date":"2021-01-30T01:45:56","date_gmt":"2021-01-30T01:45:56","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12531"},"modified":"2021-01-30T01:45:56","modified_gmt":"2021-01-30T01:45:56","slug":"fiocruz-pede-registro-da-vacina-de-oxford","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/01\/30\/fiocruz-pede-registro-da-vacina-de-oxford\/","title":{"rendered":"Fiocruz pede registro da vacina de Oxford"},"content":{"rendered":"<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) confirmou nesta sexta-feira (29) que recebeu o pedido de registro definitivo da vacina desenvolvida pela Universidade de Oxford e pela AstraZeneca, com parceria e importa\u00e7\u00e3o da tecnologia feita pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz).<\/p>\n<p>O pedido da Fiocruz ocorre ap\u00f3s processo que se iniciou em junho do ano passado, a chamada &#8220;submiss\u00e3o cont\u00ednua&#8221;. Os documentos exigidos pela Anvisa foram enviados enquanto ficavam prontos e no decorrer dos estudos, uma medida para agilizar a an\u00e1lise da reguladora.<\/p>\n<p>&#8220;Ao longo dos \u00faltimos meses, foram submetidos v\u00e1rios pacotes, com informa\u00e7\u00f5es sobre os estudos pr\u00e9-cl\u00ednicos e cl\u00ednicos, com os dados de seguran\u00e7a, efic\u00e1cia, de produ\u00e7\u00e3o e de qualidade de toda a vacina&#8221;, explica a vice-diretora de Qualidade de do Instituto de Tecnologia em Imunobiol\u00f3gicos (Bio-Manguinhos\/Fiocruz), Rosane Cuber.<\/p>\n<p><strong>De acordo com a Fiocruz:<\/strong><\/p>\n<p>* Com a chegada dos insumos para a produ\u00e7\u00e3o da vacina, 50 milh\u00f5es de doses ser\u00e3o produzidas no Brasil at\u00e9 abril;<br \/>\n* 100,4 milh\u00f5es ser\u00e3o produzidas at\u00e9 julho;<br \/>\n* No segundo semestre, uma nova importa\u00e7\u00e3o dos insumos ser\u00e1 necess\u00e1ria. De agosto a dezembro, a previs\u00e3o \u00e9 de mais 100 milh\u00f5es de doses.<\/p>\n<p>A vacina j\u00e1 estava liberada de forma emergencial, mas, a partir da poss\u00edvel aprova\u00e7\u00e3o do registro definitivo da Anvisa, a Fiocruz poder\u00e1 produzir e, caso haja uma fabrica\u00e7\u00e3o mais r\u00e1pida no futuro, at\u00e9 vender a vacina. Segundo a ag\u00eancia, o prazo m\u00e1ximo para a decis\u00e3o final de registro \u00e9 de 60 dias.<\/p>\n<p>&#8220;Quando finalizada a an\u00e1lise, o registro concedido pela Anvisa ser\u00e1 o sinal verde para que a vacina seja comercializada, distribu\u00edda e utilizada pela popula\u00e7\u00e3o, nos termos da indica\u00e7\u00e3o estabelecida na bula. O registro definitivo \u00e9 a avalia\u00e7\u00e3o completa com dados mais robustos dos estudos de qualidade, efic\u00e1cia e seguran\u00e7a, bem do plano de mitiga\u00e7\u00e3o dos riscos e da ado\u00e7\u00e3o das medidas de monitoramento&#8221;, disse a Anvisa, em nota divulgada nesta sexta.<\/p>\n<p><strong>Aposta federal<\/strong><\/p>\n<p>A vacina desenvolvida pela AstraZeneca em parceria com a Universidade de Oxford \u00e9 a principal aposta do governo federal desde o in\u00edcio das pesquisas, com parceria anunciada pelo Minist\u00e9rio da Sa\u00fade em junho de 2020.<\/p>\n<p>Desde o s\u00e1bado (23), o Brasil come\u00e7ou a aplicar 2 milh\u00f5es doses da vacina de Oxford liberadas emergencialmente e importadas da \u00cdndia, produzidas pelo Instituto Serum. Al\u00e9m disso, tamb\u00e9m nesta sexta-feira, o Minist\u00e9rio da Sa\u00fade anunciou a compra de mais 54 milh\u00f5es de doses da CoronaVac, vacina da Sicovac em produ\u00e7\u00e3o pelo Instituto Butantan, em S\u00e3o Paulo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: G1<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) confirmou nesta sexta-feira (29) que recebeu o pedido de registro definitivo da vacina desenvolvida pela Universidade de Oxford e pela AstraZeneca, com parceria e importa\u00e7\u00e3o da tecnologia feita pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). O pedido da Fiocruz ocorre ap\u00f3s processo que se iniciou em junho do ano passado, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12531"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12531\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}