{"id":12618,"date":"2021-02-02T13:28:12","date_gmt":"2021-02-02T13:28:12","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12618"},"modified":"2021-02-02T13:28:12","modified_gmt":"2021-02-02T13:28:12","slug":"covid-mundo-soma-mais-de-100-milhoes-de-vacinas-aplicadas","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/02\/covid-mundo-soma-mais-de-100-milhoes-de-vacinas-aplicadas\/","title":{"rendered":"Covid: Mundo soma mais de 100 milh\u00f5es de vacinas aplicadas"},"content":{"rendered":"<p>Mais de 100 milh\u00f5es de doses de vacinas anti-Covid j\u00e1 foram aplicadas em todo o mundo, ap\u00f3s aproximadamente dois meses do in\u00edcio das primeiras campanhas de imuniza\u00e7\u00e3o.<\/p>\n<p>Os dados s\u00e3o do portal Our World in Data, que diz que, at\u00e9 o fim desta segunda-feira (1\u00ba), 101,31 milh\u00f5es de doses j\u00e1 haviam sido administradas, sendo que mais da metade se concentra em apenas dois pa\u00edses: EUA (32,22 milh\u00f5es) e China (24 milh\u00f5es).<\/p>\n<p>J\u00e1 as 10 primeiras na\u00e7\u00f5es em n\u00fameros absolutos de doses aplicadas respondem por 86% do total. A lista ainda inclui Reino Unido (9,79 milh\u00f5es), Israel (4,99 milh\u00f5es), \u00cdndia (3,95 milh\u00f5es), Emirados \u00c1rabes Unidos (3,44 milh\u00f5es), Alemanha (2,47 milh\u00f5es), Turquia (2,14 milh\u00f5es), Brasil (2,12 milh\u00f5es) e It\u00e1lia (2,03 milh\u00f5es).<\/p>\n<p>A vacina\u00e7\u00e3o contra o novo coronav\u00edrus tamb\u00e9m evidenciou as desigualdades entre pa\u00edses: enquanto EUA, Uni\u00e3o Europeia e Reino Unido concentram 55,03 milh\u00f5es de doses, a \u00c1frica totaliza menos de 250 mil, sendo 200.081 no Marrocos, 30.861 nas Seychelles e 30 na Arg\u00e9lia.<\/p>\n<p>J\u00e1 Indon\u00e9sia, Sri Lanka e Myanmar, pa\u00edses asi\u00e1ticos densamente povoados, registram, respectivamente, 515.681, 59.154 e 3.800 doses. Em termos relativos, Israel lidera o ranking de vacina\u00e7\u00e3o, com 36,57% das pessoas tendo recebido ao menos uma dose.<\/p>\n<p>Em seguida aparecem Emirados \u00c1rabes (32,26%), Reino Unido (13,69%), Bahrein (10,16%), EUA (7,78%), Malta (5,39%), Dinamarca (3,25%), Isl\u00e2ndia (3,14%), Rom\u00eania (3,11%) e Irlanda (3,05%). O Brasil tem \u00edndice de 1%.<\/p>\n<p>Em meados de janeiro, o diretor-geral da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), Tedros Adhanom, havia alertado que o mundo estava &#8220;\u00e0 beira de uma cat\u00e1strofe moral&#8221; por conta das desigualdades nos processos de imuniza\u00e7\u00e3o contra a Covid-19.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 100 milh\u00f5es de doses de vacinas anti-Covid j\u00e1 foram aplicadas em todo o mundo, ap\u00f3s aproximadamente dois meses do in\u00edcio das primeiras campanhas de imuniza\u00e7\u00e3o. Os dados s\u00e3o do portal Our World in Data, que diz que, at\u00e9 o fim desta segunda-feira (1\u00ba), 101,31 milh\u00f5es de doses j\u00e1 haviam sido administradas, sendo que &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12618"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12618\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}