{"id":12654,"date":"2021-02-03T20:37:59","date_gmt":"2021-02-03T20:37:59","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12654"},"modified":"2021-02-03T20:37:59","modified_gmt":"2021-02-03T20:37:59","slug":"vacina-de-oxford-reduz-transmissao-apos-1a-dose-diz-estudo","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/03\/vacina-de-oxford-reduz-transmissao-apos-1a-dose-diz-estudo\/","title":{"rendered":"Vacina de Oxford reduz transmiss\u00e3o ap\u00f3s 1\u00aa dose, diz estudo"},"content":{"rendered":"<p>A vacina desenvolvida em parceria pela Oxford em parceria com o laborat\u00f3rio AstraZeneca pode reduzir a transmiss\u00e3o do novo coronav\u00edrus em at\u00e9 67,6% ap\u00f3s a aplica\u00e7\u00e3o da primeira dose. Essa foi a conclus\u00e3o de um estudo feito pelos cientistas da universidade brit\u00e2nica.<\/p>\n<p>A pesquisa, que ainda vai passar pela revis\u00e3o de pares antes da publica\u00e7\u00e3o em revista cient\u00edfica, levou em conta pela primeira vez os casos assintom\u00e1ticos e identificou que as pessoas vacinadas t\u00eam menos probabilidade de transmitir o v\u00edrus, al\u00e9m da prote\u00e7\u00e3o de n\u00e3o apresentar sintomas graves da doen\u00e7a.<\/p>\n<p>Andrew Pollard, diretor do projeto, afirmou \u00e0 rede BBC que a vacina &#8220;pode ter um impacto enorme em termos de transmiss\u00e3o&#8221;. Por\u00e9m, ele ressaltou que todos os testes foram realizados antes do surgimento das novas variantes.<\/p>\n<p>O estudo ainda mostrou que a vacina de Oxford tem 76% de efic\u00e1cia ap\u00f3s a primeira dose. Essa efic\u00e1cia sobe para 82% depois da segunda dose que \u00e9 injetada tr\u00eas meses depois da dosagem inicial.<\/p>\n<p>&#8220;Isso demonstra, para o mundo inteiro, que a vacina de Oxford funciona bem&#8221;, declarou Matt Hancock, ministro brit\u00e2nico da Sa\u00fade, para a BBC.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vacina desenvolvida em parceria pela Oxford em parceria com o laborat\u00f3rio AstraZeneca pode reduzir a transmiss\u00e3o do novo coronav\u00edrus em at\u00e9 67,6% ap\u00f3s a aplica\u00e7\u00e3o da primeira dose. Essa foi a conclus\u00e3o de um estudo feito pelos cientistas da universidade brit\u00e2nica. A pesquisa, que ainda vai passar pela revis\u00e3o de pares antes da publica\u00e7\u00e3o &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12654"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12654\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}