{"id":12669,"date":"2021-02-03T20:59:28","date_gmt":"2021-02-03T20:59:28","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=12669"},"modified":"2021-02-03T20:59:28","modified_gmt":"2021-02-03T20:59:28","slug":"bolsonaro-chega-a-69-pedidos-de-impeachment","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/03\/bolsonaro-chega-a-69-pedidos-de-impeachment\/","title":{"rendered":"Bolsonaro chega a 69 pedidos de impeachment"},"content":{"rendered":"<p>O presidente Jair Bolsonaro j\u00e1 \u00e9 alvo de 69 pedidos de impeachment . A C\u00e2mara dos deputados recebeu 68 den\u00fancias at\u00e9 agora, mas ainda h\u00e1 uma \u2013 protocolado por l\u00edderes religiosos \u2013 que aguarda assinatura digital. Com esse novo pedido, Bolsonaro supera o n\u00famero de den\u00fancias recebidas pela ex-presidente Dilma Rousseff, impeachmada em 2016 por crime n\u00e3o previsto na Lei do Impeachment.<\/p>\n<p>Entre os pedidos de impeachment contra Dilma , dois foram protocolados justamente por Jair Bolsonaro \u2014 um pedido e um aditamento \u2014 , mas as den\u00fancias n\u00e3o foram aceitas. Ao pedido do ent\u00e3o deputado, \u00e0 \u00e9poca considerado do baixo clero da C\u00e2mara, foi anexada uma peti\u00e7\u00e3o com mais de 1,8 milh\u00e3o de assinaturas a favor do impeachment. Bolsonaro denunciou a presidente por improbidade administrativa, abuso de poder e falta de decoro.<\/p>\n<p>Hoje, \u00e9 ele que enfrenta essas e outras den\u00fancias \u2014 todos os artigos que citou contra Dilma foram usados em pedidos contra ele \u2014, al\u00e9m de ter se tornado tamb\u00e9m alvo de peti\u00e7\u00f5es online pelo impeachment .<\/p>\n<p>O presidente tamb\u00e9m \u00e9 acusado de cometer crimes contra a soberania nacional e at\u00e9 contra a exist\u00eancia da Uni\u00e3o e incitar conflitos entre os tr\u00eas poderes. O tema mais recorrente entre os pedidos \u00e9 a pandemia de coronav\u00edrus : o que indica que a condu\u00e7\u00e3o da crise sanit\u00e1ria pelo governo federal, que comprou e divulgou rem\u00e9dios sem efic\u00e1cia cient\u00edfica comprovada, al\u00e9m de desestimular o isolamento social, gera grande inc\u00f4modo em atores pol\u00edticos e sociedade civil.<\/p>\n<p>A atua\u00e7\u00e3o do Ministro da Sa\u00fade, o General Eduardo Pazuello , hoje \u00e9 alvo de inqu\u00e9rito do Supremo Tribunal Federal por omiss\u00e3o quanto \u00e0 crise sanit\u00e1ria em Manaus, no estado do Amazonas. A Ag\u00eancia P\u00fablica revelou que o governo sabia da possibilidade de colapso 10 dias antes , e mostrou tamb\u00e9m a luta dos manauaras em meio \u00e0 falta de oxig\u00eanio nos hospitais.<\/p>\n<p>O segundo tema que mais aparece se refere \u00e0 participa\u00e7\u00e3o do presidente nas manifesta\u00e7\u00f5es antidemocr\u00e1ticas de mar\u00e7o e abril de 2020. Por fim, \u201cPol\u00edcia Federal\u201d \u00e9 o terceiro tema mais constante, o que indica que as den\u00fancias do ex-ministro S\u00e9rgio Moro sobre suposta interven\u00e7\u00e3o do chefe do Executivo no \u00f3rg\u00e3o, para proteger amigos e familiares, tamb\u00e9m ecoaram. A P\u00fablica analisou e resumiu todas as den\u00fancias contra Jair Bolsonaro nesta p\u00e1gina Especial \u2014 at\u00e9 o momento, a m\u00e9dia \u00e9 de um pedido a cada onze dias de governo.<\/p>\n<p>Bolsonaro vs Dilma<\/p>\n<p>Em 12 de mar\u00e7o de 2015, o ent\u00e3o deputado federal pelo Partido Progressista (PP\/RJ) protocolou pedido de impeachment contra a presidenta Dilma Rousseff (PT). Era a 19\u00aa den\u00fancia por crime de responsabilidade contra a chefe do Executivo petista \u2013 que estava em seu segundo mandato \u2013 e a 5\u00aa desde sua reelei\u00e7\u00e3o.<\/p>\n<p>A den\u00fancia comparava a situa\u00e7\u00e3o de Dilma Rousseff com a enfrentada por Fernando Collor em 1992, quando fora impeachmado. \u201cOs fatos que levaram \u00e0 cassa\u00e7\u00e3o do ex-Presidente Fernando Collor s\u00e3o bem menos graves e inconsistentes que os imputados \u00e0 Sra. Dilma Rousseff\u201d, defendeu Bolsonaro em suas redes sociais ao protocolar sua den\u00fancia \u00e0 \u00e9poca, acompanhado de uma foto em seu gabinete com homenagens aos presidentes militares M\u00e9dici e Figueiredo. Na pe\u00e7a, o proponente afirma, inclusive, que n\u00e3o havia justificativa para a condena\u00e7\u00e3o de Collor.<\/p>\n<p>O pedido de Bolsonaro contra Dilma foi baseado no Art. 88 da Constitui\u00e7\u00e3o Federal e nos artigos 4\u00ba, 7\u00ba e 9\u00ba da Lei do Impeachment (1.079\/50). As acusa\u00e7\u00f5es indicam crimes de responsabilidade contra a Constitui\u00e7\u00e3o Federal; o livre exerc\u00edcio dos direitos pol\u00edticos individuais e sociais; e a probidade na administra\u00e7\u00e3o.<\/p>\n<p>Todas essas infra\u00e7\u00f5es s\u00e3o hoje imputadas a Bolsonaro nos at\u00e9 ent\u00e3o 69 pedidos de impeachment contra o presidente \u2014 todos os pedidos e suas justificativas podem ser consultados no Especial da P\u00fablica .<\/p>\n<p>O inciso 7 do artigo 9\u00ba da Lei n\u00ba 1.079\/50 se destaca. Ele se refere \u00e0s atitudes que seriam \u201cincompat\u00edveis \u00e0 dignidade, honra e decoro do cargo\u201d. Esta parte da lei, que Bolsonaro utilizou para embasar seu pedido contra Dilma, foi muito utilizada contra ele: pelo menos 16 pedidos enfatizam que o atual presidente teria agido de forma contr\u00e1ria ao que seu cargo exige.<\/p>\n<p>As den\u00fancias v\u00e3o desde o epis\u00f3dio do Golden Shower, quando Bolsonaro compartilhou v\u00eddeo obsceno, o que foi abordado no segundo pedido de impeachment contra ele; at\u00e9 quando o presidente apoiou manifesta\u00e7\u00f5es contra outros Poderes. O endosso \u00e0s manifesta\u00e7\u00f5es antidemocr\u00e1ticas tamb\u00e9m apareceu em v\u00e1rios pedidos contra ele \u2014 29, no m\u00ednimo.<\/p>\n<p>O pedido original apresentado por Bolsonaro tamb\u00e9m acusa, sem provas, que a presidente Dilma Rousseff teria cometido \u201cevidente estelionato eleitoral\u201d, obtendo a maioria dos votos para a tramita\u00e7\u00e3o de projetos na C\u00e2mara \u201cde como question\u00e1vel\u201d, com \u201c\u2018compra\u2019 da fidelidade de aliados\u201d.<\/p>\n<p>Atualmente, as acusa\u00e7\u00f5es se voltaram contra ele. No final de 2020, em mensagem em grupo de WhatsApp dos ministros, Marcelo \u00c1lvaro Ant\u00f4nio, ent\u00e3o ministro do turismo, insinuou que o governo Bolsonaro estaria comprando apoios . \u201cUm pre\u00e7o de aprova\u00e7\u00f5es de mat\u00e9rias NUNCA VISTO ANTES NA HIST\u00d3RIA\u201d, concluiu em mensagem, com caixa-alta no original.<\/p>\n<p>Marcelo \u00c1lvaro, antes protegido, foi demitido em dezembro de 2020. Por\u00e9m, havia ficado mais de um ano no cargo, mesmo j\u00e1 investigado pelo Minist\u00e9rio P\u00fablico por esquema de candidaturas laranjas no PSL desde o in\u00edcio de 2019.<\/p>\n<p>O Pedido 0031 , protocolado por pol\u00edticos da Rede, como Jo\u00eania Wapichana, Fabiano Contarato e Randolph Frederich Rodrigues Alves, caracterizou o ministro como \u201cindemiss\u00edvel\u201d, mesmo que envolvido em \u201cdesvios de recursos de fundos eleitorais\u201d. Manter \u201cem fun\u00e7\u00f5es de alta relev\u00e2ncia da administra\u00e7\u00e3o federal, pessoas com fortes ind\u00edcios de comprometimento \u00e9tico e desvios de conduta\u201d foi citado por Bolsonaro como um crime que Dilma teria cometido.<\/p>\n<p>Deixar de assumir a responsabilidade por seus subordinados foi outro \u201c desvio de conduta \u201d vinculado \u00e0 presidente. De acordo com Jair Bolsonaro, ela teria permitido \u201cesc\u00e2ndalos envolvendo autoridades p\u00fablicas integrantes do governo\u201d. Na pe\u00e7a, argumenta que se a Comiss\u00e3o Nacional da Verdade culpou os presidentes militares pelo que acontecia em seus governos, Dilma deveria ser responsabilizada por seus subordinados.<\/p>\n<p>Esta den\u00fancia tamb\u00e9m aparece agora contra o atual presidente, no pedido de impeachment 0052, assinado por Deborah Duprat, Mauro de Azevedo, Silvio de Almeida e outros 66 autores. \u201cSua postura [de Bolsonaro] em rela\u00e7\u00e3o aos atos insensatos e desatinados levados a efeito por in\u00fameros subordinados jamais esteve \u00e0 altura da responsabilidade do cargo que ocupa\u201d, afirmam na pe\u00e7a.<\/p>\n<p>Al\u00e9m dos crimes elencados no pedido original, um ano depois, em mar\u00e7o de 2016, o autor apresentou um aditamento para incluir fatos relacionados \u00e0 condu\u00e7\u00e3o coercitiva e \u00e0 nomea\u00e7\u00e3o do ex-presidente Lula \u00e0 Casa Civil. Na pe\u00e7a, Bolsonaro transcreve a liga\u00e7\u00e3o entre Dilma e Lula que indica a nomea\u00e7\u00e3o; grava\u00e7\u00e3o sigilosa cuja divulga\u00e7\u00e3o havia sido permitida pelo juiz da Lava Jato, S\u00e9rgio Moro, mais tarde nomeado Ministro da Justi\u00e7a.<\/p>\n<p>No aditamento, Bolsonaro afirma que Dilma estaria fazendo \u201coposi\u00e7\u00e3o direta ao livre exerc\u00edcio do Poder Judici\u00e1rio\u201d em notas oficiais e entrevistas, o que enfraqueceria \u201cinstitui\u00e7\u00f5es de Estado constitucionalmente consagradas\u201d. J\u00e1 em maio do ano passado, o ex-aliado e ex-ministro da Justi\u00e7a afirmou, em outras palavras, o mesmo sobre o ent\u00e3o chefe.<\/p>\n<p>S\u00e9rgio Moro se demitiu do cargo com a justificativa de que Jair Bolsonaro estaria tentando trocar o superintendente da Pol\u00edcia Federal para acompanhar e intervir em investiga\u00e7\u00f5es de interesse \u2014 este \u00e9 o terceiro tema mais presente nos pedidos de impeachment, citado em pelo menos 17 documentos. Depois da sa\u00edda de Moro, o presidente anunciou o novo comandante da PF: Alexandre Ramagem, amigo pr\u00f3ximo da fam\u00edlia do presidente.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: iG<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro j\u00e1 \u00e9 alvo de 69 pedidos de impeachment . A C\u00e2mara dos deputados recebeu 68 den\u00fancias at\u00e9 agora, mas ainda h\u00e1 uma \u2013 protocolado por l\u00edderes religiosos \u2013 que aguarda assinatura digital. Com esse novo pedido, Bolsonaro supera o n\u00famero de den\u00fancias recebidas pela ex-presidente Dilma Rousseff, impeachmada em 2016 por &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12669"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12669\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}