{"id":13106,"date":"2021-02-21T13:28:41","date_gmt":"2021-02-21T13:28:41","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13106"},"modified":"2021-02-21T13:28:41","modified_gmt":"2021-02-21T13:28:41","slug":"csa-fica-no-zero-contra-o-murici-na-estreia","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/21\/csa-fica-no-zero-contra-o-murici-na-estreia\/","title":{"rendered":"CSA fica no zero contra o Murici na estreia"},"content":{"rendered":"<p>CSA e Murici empataram por 0 a 0, na tarde deste s\u00e1bado (20) pela 1\u00aa rodada do Alagoano Smile 2021. O jogo abriu o Estadual no Est\u00e1dio Rei Pel\u00e9. Com boa parte dos jogadores do time de Aspirantes, o Azul\u00e3o come\u00e7ou ditando o ritmo surpreendendo o Verd\u00e3o. Com o decorrer da partida, o Murici equilibrou o duelo, mas foram os donos da casa que chegaram criando boas chances de gol.<\/p>\n<p>Os times somam um ponto cada na classifica\u00e7\u00e3o do Alagoano Smile. As equipes voltam a campo na pr\u00f3xima semana. Na 2\u00aa rodada, o CSA encara o Jaciob\u00e1, na quinta-feira (25), \u00e0s 20h, no est\u00e1dio municipal Coaracy da Mata Fonseca, em Arapiraca. J\u00e1 o Murici recebe o CEO, no s\u00e1bado (27), \u00e0s 19h, no est\u00e1dio Jos\u00e9 Gomes da Costa, em Murici.<\/p>\n<p>Ainda pela abertura da competi\u00e7\u00e3o, o CRB venceu o Coruripe por WO, no est\u00e1dio Gerson Amaral, em Coruripe. Os jogadores do Hulk e a delega\u00e7\u00e3o do clube n\u00e3o foram disputar a partida e ficam com uma derrota por diferen\u00e7a de tr\u00eas gols na classifica\u00e7\u00e3o.<\/p>\n<p>Neste domingo (21) duas partidas fecham a rodada. Os dois confrontos acontecem no est\u00e1dio municipal Coaracy da Mata Fonseca, em Arapiraca. O primeiro jogo \u00e9 entre ASA x Jaciob\u00e1, \u00e0s 16h e o segundo jogo \u00e9 entre CEO x Desportivo Alian\u00e7a, \u00e0s 20h.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: FAF<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CSA e Murici empataram por 0 a 0, na tarde deste s\u00e1bado (20) pela 1\u00aa rodada do Alagoano Smile 2021. O jogo abriu o Estadual no Est\u00e1dio Rei Pel\u00e9. Com boa parte dos jogadores do time de Aspirantes, o Azul\u00e3o come\u00e7ou ditando o ritmo surpreendendo o Verd\u00e3o. Com o decorrer da partida, o Murici equilibrou &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13106"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}