{"id":13182,"date":"2021-02-23T12:10:59","date_gmt":"2021-02-23T12:10:59","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13182"},"modified":"2021-02-23T12:10:59","modified_gmt":"2021-02-23T12:10:59","slug":"aviao-com-2-milhoes-de-doses-chega-a-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/23\/aviao-com-2-milhoes-de-doses-chega-a-sao-paulo\/","title":{"rendered":"Avi\u00e3o com 2 milh\u00f5es de doses chega a S\u00e3o Paulo"},"content":{"rendered":"<p>Um avi\u00e3o com 2 milh\u00f5es de doses da vacina de Oxford\/AstraZeneca chegou ao Brasil no in\u00edcio da manh\u00e3 desta ter\u00e7a-feira (23). A aeronave posou no Aeroporto de Guarulhos e, ap\u00f3s passar por tr\u00e2mites alfandeg\u00e1rios, seguir\u00e1 para o Rio de Janeiro, onde as doses ser\u00e3o entregues \u00e0 Fiocruz.<\/p>\n<p>Na Fiocruz, as vacinas v\u00e3o passar por confer\u00eancia de temperatura e integridade da carga, receber\u00e3o etiquetas com informa\u00e7\u00f5es em portugu\u00eas e ter\u00e3o amostras encaminhadas para an\u00e1lise de protocolo e libera\u00e7\u00e3o pelo Instituto Nacional de Controle de Qualidade em Sa\u00fade.<\/p>\n<p>O processo acontecer\u00e1 ao longo do dia e a previs\u00e3o \u00e9 de que as doses estejam prontas ainda na madrugada desta quarta-feira (24) para serem incorporadas ao Plano Nacional de Imuniza\u00e7\u00e3o.<\/p>\n<p>O G1 perguntou ao Minist\u00e9rio da Sa\u00fade, na manh\u00e3 desta ter\u00e7a-feira (23), quando ser\u00e1 feita a distribui\u00e7\u00e3o das doses e quantas cada estado receber\u00e1, mas n\u00e3o obteve resposta at\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem.<\/p>\n<p>O Instituto Butantan, em S\u00e3o Paulo, tamb\u00e9m comunicou que vai entregar outros 3,4 milh\u00f5es de doses da CoronaVac esta semana.<\/p>\n<p>A expectativa inicial era a de fazer oito remessas di\u00e1rias de 426 mil. Entretanto, segundo Dimas Covas, diretor do Instituto, j\u00e1 nesta ter\u00e7a ser\u00e3o entregues 1,2 milh\u00e3o de doses.<\/p>\n<p>No s\u00e1bado, h\u00e1 a previs\u00e3o de entrega de mais dois lotes do IFA (ingrediente farmac\u00eautico ativo). Com isso, a expectativa \u00e9 que a Fiocruz produza mais 2 milh\u00f5es de doses.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: G1<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um avi\u00e3o com 2 milh\u00f5es de doses da vacina de Oxford\/AstraZeneca chegou ao Brasil no in\u00edcio da manh\u00e3 desta ter\u00e7a-feira (23). A aeronave posou no Aeroporto de Guarulhos e, ap\u00f3s passar por tr\u00e2mites alfandeg\u00e1rios, seguir\u00e1 para o Rio de Janeiro, onde as doses ser\u00e3o entregues \u00e0 Fiocruz. Na Fiocruz, as vacinas v\u00e3o passar por confer\u00eancia &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13182"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13182\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}