{"id":13292,"date":"2021-02-27T00:09:37","date_gmt":"2021-02-27T00:09:37","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13292"},"modified":"2021-02-27T00:09:37","modified_gmt":"2021-02-27T00:09:37","slug":"fiocruz-espera-insumo-para-12-mi-de-doses-amanha","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/27\/fiocruz-espera-insumo-para-12-mi-de-doses-amanha\/","title":{"rendered":"Fiocruz espera insumo para 12 mi de doses amanh\u00e3"},"content":{"rendered":"<p>Uma carga com Ingrediente Farmac\u00eautico Ativo (IFA) suficiente para fabricar 12,2 milh\u00f5es de doses de vacinas contra a covid-19 \u00e9 aguardada para este s\u00e1bado (27) pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). A remessa foi embarcada nesta sexta-feira (26) em Xangai, na China, e tem chegada prevista para as 17h50 no Aeroporto Internacional do Rio de Janeiro. As informa\u00e7\u00f5es foram divulgadas pela Fiocruz.<\/p>\n<p>Segundo a funda\u00e7\u00e3o, a nova remessa, da vacina Oxford-AstraZeneca, complementa a quantidade de insumos necess\u00e1rios para a produ\u00e7\u00e3o das 15 milh\u00f5es de doses da vacina previstas para o m\u00eas de mar\u00e7o. O primeiro lote de IFA chegou \u00e0 Fiocruz no \u00faltimo dia 6, suficiente para 2,8 milh\u00f5es de doses, que j\u00e1 est\u00e3o sendo processadas.<\/p>\n<p>\u201cAs vacinas ser\u00e3o entregues ao Programa Nacional de Imuniza\u00e7\u00f5es (PNI) ap\u00f3s o deferimento do registro pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa), cuja an\u00e1lise tem seguido de forma paralela \u00e0 produ\u00e7\u00e3o. At\u00e9 junho, a funda\u00e7\u00e3o vai receber lotes de IFA para totalizar a produ\u00e7\u00e3o de 100,4 milh\u00f5es de doses da vacina\u201d, informou a Fiocruz.<\/p>\n<p>Ap\u00f3s a chegada do IFA na Fiocruz, amostras ser\u00e3o enviadas para o controle de qualidade. Em seguida, ser\u00e3o realizados o descongelamento e o processamento final, que oacorre em quatro etapas: formula\u00e7\u00e3o, envase e recrava\u00e7\u00e3o, inspe\u00e7\u00e3o e rotulagem e embalagem. Na formula\u00e7\u00e3o, o IFA \u00e9 descongelado e dilu\u00eddo para receber estabilizadores, que garantem a integridade e preserva\u00e7\u00e3o do princ\u00edpio ativo.<\/p>\n<p>Durante o processamento da vacina, s\u00e3o retiradas amostras de todos os lotes, que s\u00e3o encaminhadas para um r\u00edgido controle de qualidade interno a fim de garantir sua seguran\u00e7a e efic\u00e1cia. Ap\u00f3s o resultado, as vacinas s\u00e3o liberadas para entrega a todos os estados brasileiros.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Ag\u00eancia Brasil<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma carga com Ingrediente Farmac\u00eautico Ativo (IFA) suficiente para fabricar 12,2 milh\u00f5es de doses de vacinas contra a covid-19 \u00e9 aguardada para este s\u00e1bado (27) pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). A remessa foi embarcada nesta sexta-feira (26) em Xangai, na China, e tem chegada prevista para as 17h50 no Aeroporto Internacional do Rio de Janeiro. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13292"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13292\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}