{"id":13341,"date":"2021-02-27T23:57:02","date_gmt":"2021-02-27T23:57:02","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13341"},"modified":"2021-02-27T23:57:02","modified_gmt":"2021-02-27T23:57:02","slug":"crb-vence-o-asa-no-rei-pele-2-a-1","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/27\/crb-vence-o-asa-no-rei-pele-2-a-1\/","title":{"rendered":"CRB vence o ASA, no Rei Pel\u00e9: 2 a 1"},"content":{"rendered":"<p>No primeiro cl\u00e1ssico estadual do ano, na tarde deste s\u00e1bado (27), no Est\u00e1dio Rei Pel\u00e9, o CRB n\u00e3o jogou bem, mas conseguiu a vit\u00f3ria sobre o ASA, por 2 a 1, com gols de Reginaldo Lopes e Hyuri, e agora soma seis pontos, na lideran\u00e7a do Campeonato Alagoano. O gol do Alvinegro foi assinalado por Martony.<\/p>\n<p>A partida deu prosseguimento \u00e0 segunda rodada do Campeonato Alagoano 2021, que foi aberta nessa quinta-feira (25), com o duelo Jaciob\u00e1 x CSA. O Alvinegro \u00e9 o 5\u00ba colocado, com um ponto na tabela do Estadual.<\/p>\n<p>O pr\u00f3ximo jogo do CRB pelo Estadual ser\u00e1 na quarta-feira (10), tamb\u00e9m no Rei Pel\u00e9, \u00e0s 20 horas, contra o Desportivo Alian\u00e7a. Mas, antes, pela Copa do Nordeste, o Alvirrubro voltar\u00e1 a campo na quarta-feira (3), contra o Fortaleza, no Castel\u00e3o, \u00e0s 19h30. J\u00e1 o ASA, pelo Alagoano, entrar\u00e1 em campo apenas na 4\u00aa rodada, no dia 13 de mar\u00e7o (s\u00e1bado), pois pela 3\u00aa rodada estar\u00e1 de folga.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Gazetaweb<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No primeiro cl\u00e1ssico estadual do ano, na tarde deste s\u00e1bado (27), no Est\u00e1dio Rei Pel\u00e9, o CRB n\u00e3o jogou bem, mas conseguiu a vit\u00f3ria sobre o ASA, por 2 a 1, com gols de Reginaldo Lopes e Hyuri, e agora soma seis pontos, na lideran\u00e7a do Campeonato Alagoano. O gol do Alvinegro foi assinalado por &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13341"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13341\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}