{"id":13358,"date":"2021-02-28T22:51:00","date_gmt":"2021-02-28T22:51:00","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13358"},"modified":"2021-02-28T22:51:00","modified_gmt":"2021-02-28T22:51:00","slug":"suspeito-de-matar-o-proprio-sogro-e-preso-apos-sofrer-acidente-em-arapiraca","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/28\/suspeito-de-matar-o-proprio-sogro-e-preso-apos-sofrer-acidente-em-arapiraca\/","title":{"rendered":"Suspeito de matar o pr\u00f3prio sogro \u00e9 preso ap\u00f3s sofrer acidente em Arapiraca"},"content":{"rendered":"<p>Suspeito de assassinar o pr\u00f3prio sogro, um homem de 26 anos foi preso ap\u00f3s sofrer um acidente de moto enquanto fugia na noite desse s\u00e1bado, 27, em Arapiraca, no Agreste de Alagoas.<\/p>\n<p>Segundo o 3\u00ba Batalh\u00e3o da Pol\u00edcia Militar, a primeira ocorr\u00eancia foi sobre um poss\u00edvel homic\u00eddio no bairro do Planalto. Ao chegar no local, os policiais encontraram o corpo de S.R.S.P, 45, alvejado com tiros de arma de fogo. Testemunhas informaram que o autor dos disparos seria genro da v\u00edtima.<\/p>\n<p>Logo em seguida, os militares foram at\u00e9 a casa do suspeito, n\u00e3o o encontraram, mas receberam den\u00fancia de um acidente de tr\u00e2nsito envolvendo uma motocicleta, com as mesmas caracter\u00edsticas da moto utilizada por ele. O homem foi atendido pelo Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia e encaminhado ao Hospital de Emerg\u00eancia do Agreste.<\/p>\n<p>No hospital, o suspeito teria admitido aos policiais que praticou o homic\u00eddio e que jogou a arma durante a fuga. A pol\u00edcia ainda realizou buscas, mas n\u00e3o encontrou o objeto. O suspeito foi preso e levado para a Central da Pol\u00edcia Civil, onde foi autuado em flagrante por homic\u00eddio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: TNH1<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suspeito de assassinar o pr\u00f3prio sogro, um homem de 26 anos foi preso ap\u00f3s sofrer um acidente de moto enquanto fugia na noite desse s\u00e1bado, 27, em Arapiraca, no Agreste de Alagoas. Segundo o 3\u00ba Batalh\u00e3o da Pol\u00edcia Militar, a primeira ocorr\u00eancia foi sobre um poss\u00edvel homic\u00eddio no bairro do Planalto. Ao chegar no local, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13358"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13358\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}