{"id":13364,"date":"2021-02-28T22:58:41","date_gmt":"2021-02-28T22:58:41","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13364"},"modified":"2021-02-28T22:58:41","modified_gmt":"2021-02-28T22:58:41","slug":"toquio-2020-deve-ter-torcida-em-numero-limitado","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/02\/28\/toquio-2020-deve-ter-torcida-em-numero-limitado\/","title":{"rendered":"T\u00f3quio-2020 deve ter torcida em n\u00famero limitado"},"content":{"rendered":"<p>A presen\u00e7a ou n\u00e3o de torcedores nos Jogos Ol\u00edmpicos de T\u00f3quio sendo sendo uma das maiores inc\u00f3gnitas sobre a realiza\u00e7\u00e3o do evento em 2021. Com os n\u00fameros da pandemia de coronav\u00edrus ainda crescendo em diversos pa\u00edses e sem a previs\u00e3o de que a popula\u00e7\u00e3o japonesa esteja vacinada at\u00e9 julho, h\u00e1 o medo de que novos surtos se propaguem no pa\u00eds. Ainda assim, a presidente do Comit\u00ea Organizador de T\u00f3quio, Seiko Hashimoto, afirmou que os Jogos devem ter torcida em n\u00famero limitado neste domingo.<\/p>\n<p>&#8220;Quando pensamos na possibilidade de realizar as Olimp\u00edadas sem torcedores nas arquibancadas, os atletas definitivamente se perguntam por que n\u00e3o h\u00e1 torcedores apenas para as Olimp\u00edadas e Paralimp\u00edadas quando outras competi\u00e7\u00f5es est\u00e3o permitindo a presen\u00e7a de espectadores. Todo mundo quer uma decis\u00e3o antecipada sobre a dire\u00e7\u00e3o a ser tomada em rela\u00e7\u00e3o aos f\u00e3s para preparar os ingressos e as acomoda\u00e7\u00f5es nos hot\u00e9is&#8221;, afirmou Hashimoto ao jornal Asahi Shimbun.<\/p>\n<p>Uma reuni\u00e3o sobre o assunto est\u00e1 marcada para acontecer na pr\u00f3xima semana, com a participa\u00e7\u00e3o do Comit\u00ea Ol\u00edmpico Internacional (COI) e outras entidades envolvidas na organiza\u00e7\u00e3o da Olimp\u00edada. De acordo com o jornal Kyodo News, a decis\u00e3o ser\u00e1 dividida em duas: primeiro, se torcedores estrangeiros ser\u00e3o permitidos no Jap\u00e3o e, depois, o n\u00famero de pessoas que poder\u00e3o ficar nas arquibancadas.<\/p>\n<p>Thomas Bach, presidente do COI, afirmou na \u00faltima semana que esta decis\u00e3o dever\u00e1 ser feito no m\u00e1ximo at\u00e9 maio.<\/p>\n<p>Muitos ingressos j\u00e1 haviam sido vendidos antes da pandemia: mais de 4,48 milh\u00f5es, al\u00e9m de mais de 970 mil que haviam sido comprados para as Paralimp\u00edadas. Ap\u00f3s o adiamento da Olimp\u00edada para 2021, os bilhetes ganharam nova validade e v\u00e3o dar acesso \u00e0s arquibancadas caso a torcida seja permitida. Apenas 810 mil pessoas pediram reembolso das entradas depois do adiamento. A expectativa do Comit\u00ea Organizador era arrecadar mais de R$ 4,8 bilh\u00f5es com a venda de ingressos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A presen\u00e7a ou n\u00e3o de torcedores nos Jogos Ol\u00edmpicos de T\u00f3quio sendo sendo uma das maiores inc\u00f3gnitas sobre a realiza\u00e7\u00e3o do evento em 2021. Com os n\u00fameros da pandemia de coronav\u00edrus ainda crescendo em diversos pa\u00edses e sem a previs\u00e3o de que a popula\u00e7\u00e3o japonesa esteja vacinada at\u00e9 julho, h\u00e1 o medo de que novos &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13364"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13364\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}