{"id":13469,"date":"2021-03-04T02:19:30","date_gmt":"2021-03-04T02:19:30","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13469"},"modified":"2021-03-04T02:19:30","modified_gmt":"2021-03-04T02:19:30","slug":"rizek-elogia-o-desabafo-de-lisca-sobre-a-covid-19","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/04\/rizek-elogia-o-desabafo-de-lisca-sobre-a-covid-19\/","title":{"rendered":"Rizek elogia o desabafo de Lisca sobre a Covid-19"},"content":{"rendered":"<p>O apresentador Andr\u00e9 Rizek, do SporTV, elogiou o desabafo de Lisca, t\u00e9cnico do Am\u00e9rica-MG, sobre o descontrole da pandemia do novo coronav\u00edrus no pa\u00eds. Nas redes sociais, ele parabenizou o treinador, que pediu que a CBF repense a manuten\u00e7\u00e3o de jogos da Copa do Brasil e falou sobre a perda de amigos em entrevista ao Premiere nesta noite, antes da partida do Coelho pelo Campeonato Mineiro.<\/p>\n<p>&#8211; Lisca mostra que doido s\u00e3o os outros. Parab\u00e9ns ao t\u00e9cnico do Am\u00e9rica. \u00c9 isso a\u00ed &#8211; escreveu Rizek em sua conta no Twitter.<\/p>\n<p>A CBF definiu em sorteio nesta semana os confrontos da primeira fase da Copa do Brasil, que vai ocorrer nas pr\u00f3ximas duas semanas. Nessa fase, a competi\u00e7\u00e3o conta com 80 clubes, que ter\u00e3o que fazer longas viagens. O Am\u00e9rica do Lisca viajar\u00e1 \u00e0 Para\u00edba para enfrentar o Treze, dia 18.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O apresentador Andr\u00e9 Rizek, do SporTV, elogiou o desabafo de Lisca, t\u00e9cnico do Am\u00e9rica-MG, sobre o descontrole da pandemia do novo coronav\u00edrus no pa\u00eds. Nas redes sociais, ele parabenizou o treinador, que pediu que a CBF repense a manuten\u00e7\u00e3o de jogos da Copa do Brasil e falou sobre a perda de amigos em entrevista ao &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13469"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13469\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}