{"id":13514,"date":"2021-03-05T11:36:03","date_gmt":"2021-03-05T11:36:03","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13514"},"modified":"2021-03-05T11:36:03","modified_gmt":"2021-03-05T11:36:03","slug":"bbb21-proximo-paredao-sera-falso","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/05\/bbb21-proximo-paredao-sera-falso\/","title":{"rendered":"BBB21: Pr\u00f3ximo pared\u00e3o ser\u00e1 falso"},"content":{"rendered":"<p>Foi anunciado nesta quinta-feira (4), no programa que definiu a lideran\u00e7a desta semana, vencida pelo sertanejo Rodolffo, que o pr\u00f3ximo pared\u00e3o do \u201cBBB21\u201d ser\u00e1 falso. Ou seja, o \u201celiminado\u201d escolhido pelo p\u00fablico sair\u00e1 da casa, mas ficar\u00e1 alguns dias em um quarto secreto para assistir o restante dos brothers por alguns dias e, depois, voltar para a casa cheio de informa\u00e7\u00f5es.<\/p>\n<p>O apresentador Tiago Leifert explicou como funcionar\u00e1 toda a din\u00e2mica desta rodada do reality, que foi pensada especialmente para dar diversas alternativas para que o p\u00fablico escolha algum participante que saiba como usar as informa\u00e7\u00f5es que ter\u00e1 acesso.<\/p>\n<p>Rodolffo, por ter vencido a prova do l\u00edder, ter\u00e1 duas semanas de imunidade e o direito de vetar uma pessoa da prova do l\u00edder da pr\u00f3xima semana. No domingo (7), o cantor indicar\u00e1 duas pessoas ao pared\u00e3o, uma do grupo VIP e outro da Xepa. O terceiro indicado ao pared\u00e3o se dar\u00e1 pelos votos dos brothers no confession\u00e1rio.<\/p>\n<p>Por \u00faltimo, os dois indicados por Rodolffo ter\u00e3o contragolpes, escolhendo cada um uma outra pessoa para o pared\u00e3o, fechando em cinco amea\u00e7ados. Disputam a prova Bate e Volta: o mais votado pela casa, o indicado pelo contragolpe da Xepa e o indicado pelo contragolpe do VIP.<\/p>\n<p>O vencedor da prova escapa do pared\u00e3o. Os outros quatro indicados disputar\u00e3o o voto do p\u00fablico, que deve votar para escolher quem ir\u00e1 para o quarto secreto.<\/p>\n<p>N\u00e3o acaba por a\u00ed: todos os quatro indicados ao pared\u00e3o falso garantem participa\u00e7\u00e3o na prova do l\u00edder da semana que vem, n\u00e3o podendo ser vetados pelo l\u00edder Rodolffo.<\/p>\n<p>O escolhido do p\u00fablico para ir para o quarto secreto ganha a chance de anular a decis\u00e3o do Anjo num prazo de duas semanas. Ou seja, ela pode escolher anular a imunidade do Anjo na semana que vem ou na semana seguinte.<\/p>\n<p>O segundo e o terceiro colocados do pared\u00e3o falso, como dito anteriormente, garantem apenas a participa\u00e7\u00e3o na pr\u00f3xima prova do l\u00edder, mas o quarto colocado, al\u00e9m de tamb\u00e9m participar da prova do l\u00edder, ganha voto com peso 2 no confession\u00e1rio, tamb\u00e9m em um prazo de duas semanas. Ou seja, pode escolher usar esse poder na semana que vem ou na semana seguinte.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: ISTO\u00c9 Gente<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi anunciado nesta quinta-feira (4), no programa que definiu a lideran\u00e7a desta semana, vencida pelo sertanejo Rodolffo, que o pr\u00f3ximo pared\u00e3o do \u201cBBB21\u201d ser\u00e1 falso. Ou seja, o \u201celiminado\u201d escolhido pelo p\u00fablico sair\u00e1 da casa, mas ficar\u00e1 alguns dias em um quarto secreto para assistir o restante dos brothers por alguns dias e, depois, voltar &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13514"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13514\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}