{"id":13550,"date":"2021-03-07T15:58:26","date_gmt":"2021-03-07T15:58:26","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13550"},"modified":"2021-03-07T15:58:26","modified_gmt":"2021-03-07T15:58:26","slug":"taxa-de-ocupacao-de-leitos-para-pacientes-com-covid-19-chega-a-81","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/07\/taxa-de-ocupacao-de-leitos-para-pacientes-com-covid-19-chega-a-81\/","title":{"rendered":"Taxa de ocupa\u00e7\u00e3o de leitos para pacientes com Covid-19 chega a 81%"},"content":{"rendered":"<p>Boletim atualizado nesse s\u00e1bado (06), que traz a distribui\u00e7\u00e3o de pacientes internados com o novo coronav\u00edrus na rede hospitalar, revela o aumento da taxa de ocupa\u00e7\u00e3o de leitos da Unidade de Terapia Intensiva (UTI) nas \u00faltimas 24 horas. Em Alagoas, nessa sexta-feira (05), o percentual era de 78%, saltando s\u00e1bado para 81%.<\/p>\n<p>Se forem levados em conta apenas os leitos de Macei\u00f3, a taxa de ocupa\u00e7\u00e3o chegou a 78%, com 136 interna\u00e7\u00f5es. J\u00e1 no interior a situa\u00e7\u00e3o continua grave e chegou a 84%, com 107 interna\u00e7\u00f5es, ultrapassando a margem de seguran\u00e7a indicada pelo Subcomit\u00ea de Epidemiologia ligado ao Comit\u00ea Cient\u00edfico do Cons\u00f3rcio Nordeste.<\/p>\n<p>Nesse s\u00e1bado, 530 novos casos e 13 mortes por Covid-19 foram confirmados em Alagoas. Desta forma, o estado tem um total de 134.949 casos confirmados e 3.073 \u00f3bitos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Gazetaweb<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boletim atualizado nesse s\u00e1bado (06), que traz a distribui\u00e7\u00e3o de pacientes internados com o novo coronav\u00edrus na rede hospitalar, revela o aumento da taxa de ocupa\u00e7\u00e3o de leitos da Unidade de Terapia Intensiva (UTI) nas \u00faltimas 24 horas. Em Alagoas, nessa sexta-feira (05), o percentual era de 78%, saltando s\u00e1bado para 81%. Se forem levados &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13550"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13550\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}