{"id":13559,"date":"2021-03-07T16:17:31","date_gmt":"2021-03-07T16:17:31","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13559"},"modified":"2021-03-07T16:17:31","modified_gmt":"2021-03-07T16:17:31","slug":"crb-bate-o-sport-por-2-a-0-pela-copa-do-nordeste","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/07\/crb-bate-o-sport-por-2-a-0-pela-copa-do-nordeste\/","title":{"rendered":"CRB bate o Sport por 2 a 0 pela Copa do Nordeste"},"content":{"rendered":"<p>Ap\u00f3s a derrota na estreia para o Fortaleza, o CRB se recuperou e conquistou seus primeiros tr\u00eas pontos na Copa do Nordeste. No Rei Pel\u00e9, o Galo bateu o Sport por 1 a 0, dominando os pernambucanos, que vieram a campo com um time alternativo, do in\u00edcio ao fim. O Regatas chegou a sofrer uma press\u00e3o no final, mas conseguiu se segurar e garantir a vit\u00f3ria em casa. Luc\u00e3o e Wesley marcaram o gols do triunfo alvirrubro.<\/p>\n<p>Com este resultado, o Galo salta da vice-lanterna para a terceira coloca\u00e7\u00e3o do Grupo A, com tr\u00eas pontos. J\u00e1 o Le\u00e3o da Ilha, que ainda n\u00e3o venceu na competi\u00e7\u00e3o, segue com um ponto e ocupa a pen\u00faltima coloca\u00e7\u00e3o do Grupo B.<\/p>\n<p>Agora, o Regatas d\u00e1 uma pausa no Nordest\u00e3o para focar no Alagoano. Na pr\u00f3xima quarta (10), \u00e0s 20h, o time alvirrubro receber\u00e1 o estreante sensa\u00e7\u00e3o Desportivo Alian\u00e7a partida que fecha a terceira rodada do torneio. O Sport, por sua vez, voltar\u00e1 a campo somente no pr\u00f3ximo s\u00e1bado (13), \u00e0s 20h30, enfrentando o 4 de Julho-PI ainda pela Lampions League, na Ilha do Retiro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Gazetaweb<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a derrota na estreia para o Fortaleza, o CRB se recuperou e conquistou seus primeiros tr\u00eas pontos na Copa do Nordeste. No Rei Pel\u00e9, o Galo bateu o Sport por 1 a 0, dominando os pernambucanos, que vieram a campo com um time alternativo, do in\u00edcio ao fim. O Regatas chegou a sofrer uma &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13560,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13559"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13559\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}