{"id":13716,"date":"2021-03-12T13:56:17","date_gmt":"2021-03-12T13:56:17","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13716"},"modified":"2021-03-12T13:56:17","modified_gmt":"2021-03-12T13:56:17","slug":"arbitro-urina-dentro-de-campo-na-copa-do-brasil","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/12\/arbitro-urina-dentro-de-campo-na-copa-do-brasil\/","title":{"rendered":"\u00c1rbitro urina dentro de campo na Copa do Brasil"},"content":{"rendered":"<p>A arbitragem no futebol brasileiro voltou \u00e0 cena na Copa do Brasil. E n\u00e3o por erros ou acertos ou ainda abuso do uso do VAR. Desta vez, o caso \u00e9 mais inusitado. Momentos antes de dar in\u00edcio ao jogo entre Boavista e Goi\u00e1s, pela primeira fase da Copa do Brasil, nesta quinta-feira, o \u00e1rbitro D\u00eanis da Silva Ribeiro, de Alagoas, simplesmente urinou no gramado de costas para o banco de reservas, \u00fanico lugar onde tinha gente no est\u00e1dio.<\/p>\n<p>Ele n\u00e3o levou em considera\u00e7\u00e3o que a partida estava sendo transmitida e havia TV no local, como em quase todos os jogos profissionais no Brasil. O torneio \u00e9 nacional e um dos mais rent\u00e1veis para os clubes no calend\u00e1rio.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">\u00c1rbitro D\u00eanis da Silva Ribeiro Serafim urina no short no meio do campo, antes da partida entre Goi\u00e1s e Boavista pela Copa do Brasil 2021. <a href=\"https:\/\/t.co\/pDrUWBbXTs\">pic.twitter.com\/pDrUWBbXTs<\/a><\/p>\n<p>&mdash; Tver (@tverdigital) <a href=\"https:\/\/twitter.com\/tverdigital\/status\/1370190262081884161?ref_src=twsrc%5Etfw\">March 12, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>O \u00e1rbitro, chamado no passado de &#8220;sua senhoria&#8221; numa alus\u00e3o ao fato de que \u00e9 ele quem manda na disputa, n\u00e3o quis correr para o vesti\u00e1rio dado o adiantado da hora e fez sua necessidade ali mesmo, sem baixar o cal\u00e7\u00e3o, numa das cenas mais inusitadas neste ano do futebol brasileiro.<\/p>\n<p>O gesto deixou incr\u00e9dulos os torcedores nas redes sociais, que n\u00e3o acreditaram no que estavam vendo. A prov\u00e1vel urina escorreu por entre seu uniforme e pernas. Depois disso, o \u00e1rbitro amarrou o cal\u00e7\u00e3o e deu in\u00edcio ao jogo. Em 90 minutos, o Boavista, do Rio, ganhou de 3 a 1 e eliminou o Goi\u00e1s. O jogo ocorreu em Saquarema. O juiz n\u00e3o fez qualquer coment\u00e1rio ap\u00f3s a partida.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A arbitragem no futebol brasileiro voltou \u00e0 cena na Copa do Brasil. E n\u00e3o por erros ou acertos ou ainda abuso do uso do VAR. Desta vez, o caso \u00e9 mais inusitado. Momentos antes de dar in\u00edcio ao jogo entre Boavista e Goi\u00e1s, pela primeira fase da Copa do Brasil, nesta quinta-feira, o \u00e1rbitro D\u00eanis &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13716"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13716\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}