{"id":13973,"date":"2021-03-21T16:01:06","date_gmt":"2021-03-21T16:01:06","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=13973"},"modified":"2021-03-21T16:01:06","modified_gmt":"2021-03-21T16:01:06","slug":"csa-derrota-o-santa-cruz-pela-copa-do-nordeste","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/21\/csa-derrota-o-santa-cruz-pela-copa-do-nordeste\/","title":{"rendered":"CSA derrota o Santa Cruz pela Copa do Nordeste"},"content":{"rendered":"<p>Neste s\u00e1bado (20), o CSA entrou em campo pela quarta rodada da Copa do Nordeste 2021. No Est\u00e1dio Jos\u00e9 do Rego Maciel, a equipe do Azul\u00e3o visitou o Santa Cruz e venceu por 2 a 1. Com dois gols do artilheiro Dellatorre, o time marujo enfim conquistou a sua primeira vit\u00f3ria no Nordest\u00e3o. Chiquinho, de p\u00eanalti, descontou para o Tricolor.<\/p>\n<p><strong>Panorama<\/strong><\/p>\n<p>Com a vit\u00f3ria, o Azul\u00e3o entrou momentaneamente no G-4 do grupo B, com 6 pontos. J\u00e1 o Tricolor, faz uma campanha muito ruim e segue sem conquistar nenhuma vit\u00f3ria na competi\u00e7\u00e3o, amargando a lanterna do grupo A, com nenhum ponto.<\/p>\n<p><strong>A pr\u00f3xima<\/strong><\/p>\n<p>Agora, a equipe maruja volta todas as suas aten\u00e7\u00f5es para o seu pr\u00f3ximo desafio. Na ter\u00e7a-feira (23), ainda pela Copa do Nordeste, o Azul\u00e3o do Mutange recebe o Bahia. A partida ser\u00e1 disputada \u00e0s 21h30, no Est\u00e1dio Rei Pel\u00e9, em Macei\u00f3.<\/p>\n<p>J\u00e1 o Tricolor, viaja at\u00e9 o Cear\u00e1 para enfrentar o Fortaleza, tamb\u00e9m na ter\u00e7a, \u00e0s 21h, na Arena Castel\u00e3o, pela sequ\u00eancia do Nordest\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Gazetaweb<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado (20), o CSA entrou em campo pela quarta rodada da Copa do Nordeste 2021. No Est\u00e1dio Jos\u00e9 do Rego Maciel, a equipe do Azul\u00e3o visitou o Santa Cruz e venceu por 2 a 1. Com dois gols do artilheiro Dellatorre, o time marujo enfim conquistou a sua primeira vit\u00f3ria no Nordest\u00e3o. Chiquinho, de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13973"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13973\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}