{"id":14072,"date":"2021-03-24T11:36:43","date_gmt":"2021-03-24T11:36:43","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14072"},"modified":"2021-03-24T11:36:43","modified_gmt":"2021-03-24T11:36:43","slug":"presidente-da-cbf-defende-jogos-em-meio-a-pandemia","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/24\/presidente-da-cbf-defende-jogos-em-meio-a-pandemia\/","title":{"rendered":"Presidente da CBF defende jogos em meio \u00e0 pandemia"},"content":{"rendered":"<p>Em meio ao pior momento da pandemia do novo coronav\u00edrus no Brasil, o presidente da CBF (Confedera\u00e7\u00e3o Brasileira de Futebol), Rog\u00e9rio Caboclo, defendeu em reuni\u00e3o virtual com os principais clubes do Pa\u00eds no \u00faltimo dia 10 que o calend\u00e1rio do futebol deveria seguir normalmente, sem interrup\u00e7\u00e3o. O v\u00eddeo do encontro foi divulgado pelo jornal O Dia nesta ter\u00e7a-feira.<\/p>\n<p>&#8220;Eu vou mandar no futebol brasileiro e vou determinar que vai ter competi\u00e7\u00e3o. Porque voc\u00eas est\u00e3o f&#8230; se n\u00e3o tiver. Eu assumo o \u00f4nus por todos voc\u00eas&#8221;, disse Caboclo aos presidentes de clubes.<\/p>\n<p>Durante o encontro, o dirigente afirma ainda que a Rede Globo, emissora que det\u00e9m os direitos de transmiss\u00e3o dos principais torneios da temporada, tamb\u00e9m n\u00e3o tem inten\u00e7\u00e3o de paralisar os jogos. &#8220;Vamos pensar agora: n\u00f3s podemos parar o futebol? A Rede Globo n\u00e3o quer. Ningu\u00e9m quer (parar o futebol), seus patrocinadores n\u00e3o querem. E, se parar, sabe quando n\u00f3s temos a seguran\u00e7a de dizer que a gente pode voltar? Nunca&#8221;, falou Caboclo em determinado trecho da reuni\u00e3o (veja nota da emissora abaixo)<\/p>\n<p>Entre os representantes dos clubes que aparecem na videochamada est\u00e3o Rodolfo Landim, do Flamengo, Jorge Salgado, do Vasco, Du\u00edlio Monteiro Alves, do Corinthians, Maur\u00edcio Galiotte, do Palmeiras, e Guilherme Belintani, do Bahia. O presidente do Palmeiras tenta fazer com que o assunto seja tratado em outro momento por achar a quest\u00e3o mais ampla, mas Caboclo n\u00e3o concorda.<\/p>\n<p>Por fim, diante do clima de tens\u00e3o, Caboclo diz ter telefonemas para atender e encerra o encontro com a seguinte pergunta. &#8220;Algum presidente aqui presente \u00e9 contra a continuidade (do calend\u00e1rio)?&#8221; Diante do sil\u00eancio dos dirigentes, ele finaliza a chamada.<\/p>\n<p>A pandemia do novo coronav\u00edrus j\u00e1 afeta mais da metade dos campeonatos estaduais e, consequentemente, a agenda dos clubes brasileiros. Enquanto o Pa\u00eds se aproxima da triste marca de 300 mil mortes causadas pela doen\u00e7a, os torneios regionais n\u00e3o t\u00eam conseguido ficar imunes \u00e0 devasta\u00e7\u00e3o causada pela covid-19. Levantamento feito pelo Estad\u00e3o mostra que, dos 27 torneios regionais deste in\u00edcio de temporada, pelo menos 16 enfrentam algum tipo de restri\u00e7\u00e3o.<\/p>\n<p>As competi\u00e7\u00f5es organizadas pela CBF, no entanto, n\u00e3o foram paralisadas. A Copa do Brasil, por exemplo, teve seus jogos transferidos para localidades nas quais a pr\u00e1tica de atividades esportivas est\u00e1 autorizada.<\/p>\n<p>Leia a nota da Globo:<\/p>\n<p><em>&#8220;Como vem fazendo desde o in\u00edcio da pandemia h\u00e1 mais de um ano, a Globo segue respeitando as orienta\u00e7\u00f5es dadas pelas autoridades competentes e acompanhando as decis\u00f5es dos organizadores das competi\u00e7\u00f5es. Entendemos que o momento \u00e9 de cautela, e que a prioridade \u00e9 a seguran\u00e7a de todos. Vamos seguir e respeitar todos os protocolos que forem definidos e decididos pelas entidades.&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio ao pior momento da pandemia do novo coronav\u00edrus no Brasil, o presidente da CBF (Confedera\u00e7\u00e3o Brasileira de Futebol), Rog\u00e9rio Caboclo, defendeu em reuni\u00e3o virtual com os principais clubes do Pa\u00eds no \u00faltimo dia 10 que o calend\u00e1rio do futebol deveria seguir normalmente, sem interrup\u00e7\u00e3o. O v\u00eddeo do encontro foi divulgado pelo jornal O &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14072"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14072\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}