{"id":14099,"date":"2021-03-25T13:57:58","date_gmt":"2021-03-25T13:57:58","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14099"},"modified":"2021-03-25T13:57:58","modified_gmt":"2021-03-25T13:57:58","slug":"flamengo-vence-o-botafogo-e-assume-a-lideranca-do-carioca","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/25\/flamengo-vence-o-botafogo-e-assume-a-lideranca-do-carioca\/","title":{"rendered":"Flamengo vence o Botafogo e assume a lideran\u00e7a do Carioca"},"content":{"rendered":"<p>Ainda atuando sem os principais nomes do elenco profissional, o Flamengo venceu o Botafogo nesta quarta, no Nilton Santos, e assumiu a lideran\u00e7a da Ta\u00e7a Guanabara. A vit\u00f3ria por 2 a 0 veio com mais um gol de Rodrigo Muniz &#8211; artilheiro do Carioca -, que entrou no lugar do Pedro ainda no primeiro tempo, e outro de Hugo Moura, j\u00e1 nos minutos finais do cl\u00e1ssico no Nilton Santos.<\/p>\n<p>O Flamengo demonstrou estar mesmo em outro patamar em rela\u00e7\u00e3o ao rival, que, em in\u00edcio de trabalho com o t\u00e9cnico Marcelo Chamusca, ainda precisa de ajustes. Apesar de alguns sustos na etapa final, o Rubro-Negro teve o controle da partida no Nilton Santos, mas tamb\u00e9m desperdi\u00e7ou v\u00e1rias oportunidades.<\/p>\n<p>No pr\u00f3ximo s\u00e1bado, \u00e0s 21h05, o Flamengo visita o Boavista. O Botafogo, por sua vez, enfrenta o Nova Igua\u00e7u, tamb\u00e9m como visitante, no domingo, \u00e0s 18h. As duas partidas pelo Estadual ser\u00e3o em Bacax\u00e1, no Est\u00e1dio Elcyr Resende.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Terra<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainda atuando sem os principais nomes do elenco profissional, o Flamengo venceu o Botafogo nesta quarta, no Nilton Santos, e assumiu a lideran\u00e7a da Ta\u00e7a Guanabara. A vit\u00f3ria por 2 a 0 veio com mais um gol de Rodrigo Muniz &#8211; artilheiro do Carioca -, que entrou no lugar do Pedro ainda no primeiro tempo, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14099"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14099\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}