{"id":14157,"date":"2021-03-26T19:21:23","date_gmt":"2021-03-26T19:21:23","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14157"},"modified":"2021-03-26T19:21:23","modified_gmt":"2021-03-26T19:21:23","slug":"renan-filho-sanciona-lei-que-autoriza-compra-da-sputnik-v-para-acelerar-vacinacao","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/26\/renan-filho-sanciona-lei-que-autoriza-compra-da-sputnik-v-para-acelerar-vacinacao\/","title":{"rendered":"Renan Filho sanciona lei que autoriza compra da Sputnik V para acelerar vacina\u00e7\u00e3o"},"content":{"rendered":"<p>A Sputnik V vem a\u00ed. A lei que permite a aquisi\u00e7\u00e3o do imunizante russo pelo Estado de Alagoas foi sancionada pelo governador Renan Filho. \u201cFoi um passo muito importante para assinarmos com o Fundo Soberano Russo e assim avan\u00e7armos na aquisi\u00e7\u00e3o da Sputnik\u201d, confirmou o gestor, em an\u00fancio foi publicado nas redes sociais na manh\u00e3 desta sexta-feira (26).<\/p>\n<p>O governador prev\u00ea a chegada do primeiro lote j\u00e1 no pr\u00f3ximo m\u00eas de abril. \u201cCom isso, vamos potencializar o Plano Nacional de Imuniza\u00e7\u00e3o para garantir, o quanto antes, a vacina\u00e7\u00e3o do povo de Alagoas e do povo brasileiro\u201d, estimou Renan Filho.<\/p>\n<p>Com 91,6% de efic\u00e1cia comprovada, de acordo com estudo publicado na conceituada revista cient\u00edfica Lancet, a Sputnik foi negociada em 56 pa\u00edses e teve 80 milh\u00f5es de doses compradas pelo Governo Federal e por diversas cidades e estados brasileiros, como a Bahia, o Paran\u00e1 e o Mato Grosso, que aguardam a libera\u00e7\u00e3o da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa).<\/p>\n<p>Em Alagoas, a compra da vacina desenvolvida no pa\u00eds europeu soma um investimento aproximado de 21 milh\u00f5es de d\u00f3lares para os cofres p\u00fablicos \u2013 a depender da taxa de cambio no dia. Em mensagem especialmente dirigida aos parlamentares alagoanos, o chefe do Executivo estadual esclareceu o veto proferido a um dos termos \u2013 relacionado \u00e0 libera\u00e7\u00e3o or\u00e7ament\u00e1ria \u2013 da lei inicialmente aprovada pela Assembleia Legislativa de Alagoas. \u201cNa san\u00e7\u00e3o de hoje, fiz um veto porque, para adquirir as vacinas, vamos precisar remanejar um volume consider\u00e1vel de recursos\u201d, justificou.<\/p>\n<p>Explica-se: como o Estado n\u00e3o sabia que teria autoriza\u00e7\u00e3o para adquirir os imunizantes, n\u00e3o provisionou os recursos necess\u00e1rios no or\u00e7amento. Com isso, o montante ser\u00e1 remanejado de outras rubricas or\u00e7ament\u00e1rias. Os deputados autorizaram o remanejamento, entretanto, o segundo par\u00e1grafo do artigo segundo da Lei determina que o Estado deve cumprir o limite de remanejamento estabelecido na Lei Or\u00e7ament\u00e1ria. \u201cComo o limite est\u00e1 muito pr\u00f3ximo do final n\u00e3o daria para remanejar e cumprir o limite\u201d, explicou o governador.<\/p>\n<p>\u201cComo eu acredito que os parlamentares n\u00e3o desejariam impedir o estado de comprar a vacina \u2013 ao contr\u00e1rio, visto que a vota\u00e7\u00e3o foi por ampla maioria \u2013, eu estou vetando esse artigo porque assim vamos conseguir assinar o contrato, comprar a vacina Sputnik e acelerar a vacina\u00e7\u00e3o em Alagoas e no Brasil\u201d, reiterou.<\/p>\n<p>Ao final do esclarecimento, Renan Filho assinalou que, em Alagoas, as institui\u00e7\u00f5es defendem a vacina: \u201cO Governo do Estado, o Poder Legislativo, o Poder Judici\u00e1rio e o Minist\u00e9rio P\u00fablico compreendem que a vacina\u00e7\u00e3o \u00e9 a sa\u00edda mais r\u00e1pida para essa crise, ent\u00e3o, vamos trabalhar nessa dire\u00e7\u00e3o tamb\u00e9m\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Ag\u00eancia Alagoas<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sputnik V vem a\u00ed. A lei que permite a aquisi\u00e7\u00e3o do imunizante russo pelo Estado de Alagoas foi sancionada pelo governador Renan Filho. \u201cFoi um passo muito importante para assinarmos com o Fundo Soberano Russo e assim avan\u00e7armos na aquisi\u00e7\u00e3o da Sputnik\u201d, confirmou o gestor, em an\u00fancio foi publicado nas redes sociais na manh\u00e3 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14157"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14157\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}