{"id":14187,"date":"2021-03-28T14:03:05","date_gmt":"2021-03-28T14:03:05","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14187"},"modified":"2021-03-28T14:03:05","modified_gmt":"2021-03-28T14:03:05","slug":"igreja-nova-dois-homens-morrem-apos-confrontar-policiais","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/03\/28\/igreja-nova-dois-homens-morrem-apos-confrontar-policiais\/","title":{"rendered":"Igreja Nova: Dois homens morrem ap\u00f3s confrontar policiais"},"content":{"rendered":"<p>Dois homens, um deles suspeito de homic\u00eddio, morreram em uma troca de tiros com policiais no Povoado Ipiranga, em Igreja Nova, neste s\u00e1bado (27).<\/p>\n<p>Segundo a pol\u00edcia, o confronto ocorreu durante cumprimento de mandado de pris\u00e3o em desfavor de um homicida que atuava nos munic\u00edpios de Penedo e Igreja Nova. A opera\u00e7\u00e3o foi coordenada pelo delegado Gustavo Xavier, da Divis\u00e3o Especial de Investiga\u00e7\u00f5es e Capturas da Pol\u00edcia Civil (Deic).<\/p>\n<p>&#8220;O homicida e mais um elemento que estava no local do fato sacaram duas armas de fogo e efetuaram diversos disparos contra a viatura do Tigre. Houve o revide por parte da equipe de policiais, sendo atingidos os meliantes, os quais foram socorridos para o hospital de Penedo, local em que vieram a \u00f3bito&#8217;, informou a pol\u00edcia.<\/p>\n<p>O mandado de pris\u00e3o foi emitido em raz\u00e3o de um homic\u00eddio cometido no dia 16\/02\/21, o qual vitimou Genisson Felipe Alves.<\/p>\n<p>Na ocasi\u00e3o, Genisson, que tinha 28 anos, estava na \u201cBorracharia do Marcinho\u201d, localizado na Rua Bela Vista, em Igreja Nova, quando um indiv\u00edduo que estava na garupa de uma motocicleta se aproximou de forma sorrateira e efetuou in\u00fameros disparos de arma de fogo. A pol\u00edcia disse ainda que, conforme o depoimento de uma testemunha ocular, o autor teria feito quest\u00e3o de levantar a viseira do capacete antes de atirar na v\u00edtima.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: TNH1<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois homens, um deles suspeito de homic\u00eddio, morreram em uma troca de tiros com policiais no Povoado Ipiranga, em Igreja Nova, neste s\u00e1bado (27). Segundo a pol\u00edcia, o confronto ocorreu durante cumprimento de mandado de pris\u00e3o em desfavor de um homicida que atuava nos munic\u00edpios de Penedo e Igreja Nova. A opera\u00e7\u00e3o foi coordenada pelo &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14187"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}