{"id":14451,"date":"2021-04-06T12:41:45","date_gmt":"2021-04-06T12:41:45","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14451"},"modified":"2021-04-06T12:41:45","modified_gmt":"2021-04-06T12:41:45","slug":"em-momentos-opostos-csa-x-coruripe-se-enfrentam-no-campeonato-alagoano","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/04\/06\/em-momentos-opostos-csa-x-coruripe-se-enfrentam-no-campeonato-alagoano\/","title":{"rendered":"Em Momentos opostos , CSA x Coruripe se enfrentam no Campeonato Alagoano"},"content":{"rendered":"<p>Vivendo situa\u00e7\u00f5es inversas no Campeonato Alagoano 2021, o CSA recebe o Coruripe nesta ter\u00e7a-feira (6), \u00e0s 20h, no Est\u00e1dio Rei Pel\u00e9, pela 6\u00aa rodada da fase de classifica\u00e7\u00e3o do Estadual.<\/p>\n<p>A competi\u00e7\u00e3o tem em sua divis\u00e3o de elite nove equipes com o seguinte formato: na primeira fase, os times se enfrentam em turno \u00fanico. Ao final das oito rodadas, os quatro primeiros avan\u00e7am na luta pelo t\u00edtulo. E, desta vez, diferente do ano anterior, os dois piores ser\u00e3o rebaixados para segunda divis\u00e3o.<\/p>\n<p><strong>Panorama<\/strong><\/p>\n<p>O Azul\u00e3o colheu, at\u00e9 agora, oito pontos (duas vit\u00f3rias e dois empates). Deixou dois pontos escaparem na primeira rodada no empate sem gols contra o Murici, quando utilizou um time formado por juniores. Naquele momento, o plantel principal estava em pr\u00e9-temporada no CT do Retr\u00f4, em Pernambuco, e s\u00f3 foi utilizado a partir da segunda rodada do Estadual. Atualmente, o time marujo est\u00e1 ocupando a 3\u00aa coloca\u00e7\u00e3o do Estadual.<\/p>\n<p>J\u00e1 o Hulk precisa, desesperadamente, da vit\u00f3ria, at\u00e9 porque dois times v\u00e3o ser rebaixados neste ano, no Estadual. Com quatro pontos (uma vit\u00f3ria, um empate e duas derrotas), o Verd\u00e3o Praiano est\u00e1 na 7\u00aa posi\u00e7\u00e3o da tabela de classifica\u00e7\u00e3o. Um ponto \u00e0 frente do ASA, primeira equipe presente na zona da degola.<\/p>\n<p><strong>CSA<\/strong><\/p>\n<p>A escala\u00e7\u00e3o do CSA para a partida contra o Coruripe, nesta ter\u00e7a (6), deve vir com surpresas. Com a sequ\u00eancia de jogos, pelo Nordest\u00e3o, Copa do Brasil e Estadual, a tend\u00eancia \u00e9 que o t\u00e9cnico Mozart mande a campo um time misto.<\/p>\n<p><strong>Desfalques<\/strong><\/p>\n<p>As baixas recentes complicaram o trabalho do treinador, que tem um elenco enxuto nesta temporada. Ele n\u00e3o contou contra o 4 de julho com o goleiro Thiago Rodrigues (pancada na cabe\u00e7a), o lateral Cristovam (les\u00e3o muscular), o meia Nadson (panturrilha) e o zagueiro Fabr\u00edcio (ruptura no tend\u00e3o).<\/p>\n<p>O lateral Vitor Costa teve um desgaste muscular na semana passada e, por isso, entrou, apenas, no segundo tempo do jogo de s\u00e1bado (3). No primeiro, o volante Silas jogou improvisado.<\/p>\n<p><strong>Equipe<\/strong><\/p>\n<p>Al\u00e9m do desgaste, o time marujo est\u00e1 de olho no confronto decisivo contra o Sampaio Corr\u00eaa, no pr\u00f3ximo s\u00e1bado (10), pela \u00faltima rodada da fase de grupos da Copa do Nordeste. Diante disso, o treinador azulino deve poupar alguns dos seus principais titulares.<\/p>\n<p>O CSA deve ir a campo com: Darley, Norberto, Filemon (Tito), Luc\u00e3o e Jo\u00e3o Victor; Marquinhos, \u00cdtalo e Bruno Mota; Silvinho (Pimp\u00e3o), Aylon e Iury (Dellatorre).<\/p>\n<p><strong>Coruripe<\/strong><\/p>\n<p>O t\u00e9cnico Robinson Santos foi liberado para viajar at\u00e9 a cidade de S\u00e3o Paulo, para cuidar da transfer\u00eancia de sua genitora, que est\u00e1 acometida da Covid-19. As \u00faltimas informa\u00e7\u00f5es d\u00e3o conta de que a m\u00e3e do profissional receber\u00e1 alta nesta ter\u00e7a (6), e, dificilmente, o comandante estar\u00e1 no comando do time no jogo contra o CSA. Sendo assim, o auxiliar t\u00e9cnico Thiago Milit\u00e3o dever\u00e1 comandar\u00e1 a partida.<\/p>\n<p><strong>Novidade<\/strong><\/p>\n<p>O meia Jo\u00e3o Peclat, de 20 anos, foi regularizado e estar\u00e1 \u00e0 disposi\u00e7\u00e3o para encarar o CSA.<\/p>\n<p><strong>Covid-19<\/strong><\/p>\n<p>Todos os que testaram positivo no exame de Covid-19 do dia 18 de mar\u00e7o cumpriram as recomenda\u00e7\u00f5es m\u00e9dicas e foram liberados para as atividades, foram eles: o lateral Esquerdo Jordan, o volante \u00c1lvaro, o meia Hudson, o meia-atacante Rafinha. O roupeiro Jorge Fernando tamb\u00e9m retornou \u00e0s suas atividades.<\/p>\n<p>O Coruripe deve ir a campo com: Erik, Jo\u00e3o Felipe, Elton, Jess\u00e9 e Jordan; J\u00e1dson Castro, Rafinha, Polinho e Leandro Sardinha; Alisson e Gustavo.<\/p>\n<p><strong>Arbitragem<\/strong><\/p>\n<p>Rafael Carlos Salgueiro (CBF) ser\u00e1 o \u00e1rbitro. Ele ser\u00e1 auxiliado por Ana Paula dos Santos (CBF) e Maria de F\u00e1tima Mendon\u00e7a (CBF). Alisson Kayque Gomes de Lima (FAF) ser\u00e1 o quarto \u00e1rbitro. George Alves Feitoza (CBF) ser\u00e1 o analista de campo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivendo situa\u00e7\u00f5es inversas no Campeonato Alagoano 2021, o CSA recebe o Coruripe nesta ter\u00e7a-feira (6), \u00e0s 20h, no Est\u00e1dio Rei Pel\u00e9, pela 6\u00aa rodada da fase de classifica\u00e7\u00e3o do Estadual. A competi\u00e7\u00e3o tem em sua divis\u00e3o de elite nove equipes com o seguinte formato: na primeira fase, os times se enfrentam em turno \u00fanico. Ao &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14451"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14451\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}