{"id":14645,"date":"2021-04-11T22:43:12","date_gmt":"2021-04-11T22:43:12","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14645"},"modified":"2021-04-11T22:43:12","modified_gmt":"2021-04-11T22:43:12","slug":"eficacia-da-coronavac-e-maior-apos-21-dias-da-1a-dose","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/04\/11\/eficacia-da-coronavac-e-maior-apos-21-dias-da-1a-dose\/","title":{"rendered":"Efic\u00e1cia da CoronaVac \u00e9 maior ap\u00f3s 21 dias da 1\u00aa dose"},"content":{"rendered":"<p>Estudo cl\u00ednico final sobre a Coronavac divulgado neste domingo (11) mostra que a efic\u00e1cia da vacina \u00e9 maior do que nos resultados iniciais divulgados entre dezembro e janeiro. O estudo foi feito pelo Instituto Butantan, que produz a vacina em parceria com a farmac\u00eautica chinesa Sinovac.<\/p>\n<p>Segundo artigo cient\u00edfico encaminhado para revis\u00e3o e publica\u00e7\u00e3o na revista cient\u00edfica Lancet, uma das mais respeitadas do mundo, a efic\u00e1cia para casos sintom\u00e1ticos de Covid-19 atingiu 50,7%, ante os 50,38% informados inicialmente. Ou seja, a vacina reduz pela metade os novos registros de contamina\u00e7\u00e3o em uma popula\u00e7\u00e3o vacinada.<\/p>\n<p>Segundo o estudo encaminhando neste domingo, a efic\u00e1cia da CoronaVac pode chegar a 62,3% com um intervalo de mais de 21 dias entre as duas doses da vacina.<\/p>\n<p>O estudo diz, no entanto, que a efic\u00e1cia m\u00ednima da vacina j\u00e1 aparece na segunda semana depois da primeira dose.<\/p>\n<p>O \u00edndice de efic\u00e1cia global aponta a capacidade do imunizante de proteger em todos os casos \u2013 sejam eles leves, moderados ou graves. O n\u00famero m\u00ednimo recomendado pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) e tamb\u00e9m pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) \u00e9 de 50%.<\/p>\n<p>Os resultados tamb\u00e9m apontaram que para os casos que requerem assist\u00eancia m\u00e9dica a efic\u00e1cia da vacina variou entre 83,7% e 100%, quando o estudo preliminar que subsidiou a autoriza\u00e7\u00e3o do uso emergencial do imunizante no pa\u00eds indicava entre 78% e 100%.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: G1<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo cl\u00ednico final sobre a Coronavac divulgado neste domingo (11) mostra que a efic\u00e1cia da vacina \u00e9 maior do que nos resultados iniciais divulgados entre dezembro e janeiro. O estudo foi feito pelo Instituto Butantan, que produz a vacina em parceria com a farmac\u00eautica chinesa Sinovac. Segundo artigo cient\u00edfico encaminhado para revis\u00e3o e publica\u00e7\u00e3o na &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14645"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}