{"id":14783,"date":"2021-04-16T01:07:55","date_gmt":"2021-04-16T01:07:55","guid":{"rendered":"https:\/\/oparanews.com.br\/?p=14783"},"modified":"2021-04-16T01:07:55","modified_gmt":"2021-04-16T01:07:55","slug":"nova-portaria-amplia-funcionamento-do-comercio-de-penedo","status":"publish","type":"post","link":"https:\/\/www.oparanews.com.br\/index.php\/2021\/04\/16\/nova-portaria-amplia-funcionamento-do-comercio-de-penedo\/","title":{"rendered":"Nova portaria amplia funcionamento do com\u00e9rcio de Penedo"},"content":{"rendered":"<p>O com\u00e9rcio de Penedo est\u00e1 com hor\u00e1rio de funcionamento ampliado a partir de hoje, quinta-feira, 15 de abril, modifica\u00e7\u00e3o estendida para bares e restaurantes, conforme a mais recente portaria do Grupo de Gerenciamento de Crise Relacionada com a Covid-19.<\/p>\n<p>Lojas e pontos comerciais voltam a abrir \u00e0s 8 horas e fecham \u00e0s 17 horas, de ter\u00e7a \u00e0 sexta-feira.<\/p>\n<p>Bares e restaurantes podem funcionar at\u00e9 20 horas, de segunda \u00e0 sexta-feira, com 50% de sua capacidade de p\u00fablico e no sistema pegue-leve ou delivery ap\u00f3s as 20 horas, mesmo sistema para s\u00e1bado e domingo.<\/p>\n<p>Padarias, lojas de conveni\u00eancia, mercados, supermercados, minimercados, a\u00e7ougues, peixarias e estabelecimentos de alimentos funcionais e suplementos continuam funcionando normalmente, mantida a proibi\u00e7\u00e3o do consumo local de bebidas e comidas, medida prevista no protocolo sanit\u00e1rio em vigor do plano estadual de distanciamento social controlado.<\/p>\n<p>Ainda de acordo com as normas em vigor, templos, igrejas e demais institui\u00e7\u00f5es religiosas podem fazer as respectivas celebra\u00e7\u00f5es, desde que respeitando 30% de sua capacidade de p\u00fablico, sendo vedada a entrada de idosos ou pessoas com comorbidades.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Decom PMP<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O com\u00e9rcio de Penedo est\u00e1 com hor\u00e1rio de funcionamento ampliado a partir de hoje, quinta-feira, 15 de abril, modifica\u00e7\u00e3o estendida para bares e restaurantes, conforme a mais recente portaria do Grupo de Gerenciamento de Crise Relacionada com a Covid-19. Lojas e pontos comerciais voltam a abrir \u00e0s 8 horas e fecham \u00e0s 17 horas, de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14783"}],"version-history":[{"count":0,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14783\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oparanews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}